{"id":54,"date":"2023-02-02T11:17:34","date_gmt":"2023-02-02T11:17:34","guid":{"rendered":"https:\/\/teachcoalition.org\/research\/?page_id=54"},"modified":"2023-02-02T13:58:28","modified_gmt":"2023-02-02T13:58:28","slug":"blogs-page","status":"publish","type":"page","link":"https:\/\/teachcoalition.org\/research\/blogs-page\/","title":{"rendered":"Blogs Page"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-blogs.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-54","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blogs Page - Teach Research<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teachcoalition.org\/research\/blogs-page\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blogs Page - Teach Research\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teachcoalition.org\/research\/blogs-page\/\" \/>\n<meta property=\"og:site_name\" content=\"Teach Research\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T13:58:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/blogs-page\\\/\",\"url\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/blogs-page\\\/\",\"name\":\"Blogs Page - Teach Research\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/#website\"},\"datePublished\":\"2023-02-02T11:17:34+00:00\",\"dateModified\":\"2023-02-02T13:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/blogs-page\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teachcoalition.org\\\/research\\\/blogs-page\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/blogs-page\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogs Page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/#website\",\"url\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/\",\"name\":\"Teach Research\",\"description\":\"The Teach Coalition Office of Jewish Education Policy and Research (OJEPR)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teachcoalition.org\\\/research\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blogs Page - Teach Research","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teachcoalition.org\/research\/blogs-page\/","og_locale":"en_US","og_type":"article","og_title":"Blogs Page - Teach Research","og_url":"https:\/\/teachcoalition.org\/research\/blogs-page\/","og_site_name":"Teach Research","article_modified_time":"2023-02-02T13:58:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teachcoalition.org\/research\/blogs-page\/","url":"https:\/\/teachcoalition.org\/research\/blogs-page\/","name":"Blogs Page - Teach Research","isPartOf":{"@id":"https:\/\/teachcoalition.org\/research\/#website"},"datePublished":"2023-02-02T11:17:34+00:00","dateModified":"2023-02-02T13:58:28+00:00","breadcrumb":{"@id":"https:\/\/teachcoalition.org\/research\/blogs-page\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teachcoalition.org\/research\/blogs-page\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/teachcoalition.org\/research\/blogs-page\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teachcoalition.org\/research\/"},{"@type":"ListItem","position":2,"name":"Blogs Page"}]},{"@type":"WebSite","@id":"https:\/\/teachcoalition.org\/research\/#website","url":"https:\/\/teachcoalition.org\/research\/","name":"Teach Research","description":"The Teach Coalition Office of Jewish Education Policy and Research (OJEPR)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teachcoalition.org\/research\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"brizy_media":[],"_links":{"self":[{"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/pages\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":1,"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/pages\/54\/revisions"}],"predecessor-version":[{"id":55,"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/pages\/54\/revisions\/55"}],"wp:attachment":[{"href":"https:\/\/teachcoalition.org\/research\/wp-json\/wp\/v2\/media?parent=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}